{"id":6929,"date":"2025-10-29T17:54:07","date_gmt":"2025-10-29T22:54:07","guid":{"rendered":"https:\/\/www.ljsexpress.com\/?post_type=product&#038;p=6929"},"modified":"2025-10-29T17:56:19","modified_gmt":"2025-10-29T22:56:19","slug":"cartera-bolso-ceuzado-para-dama","status":"publish","type":"product","link":"https:\/\/www.ljsexpress.com\/es_pe\/producto\/cartera-bolso-ceuzado-para-dama\/","title":{"rendered":"Cartera Bolso Cruzado para Dama"},"content":{"rendered":"<h2><strong>Cartera Bolso Cruzado para Dama<\/strong><\/h2>\n<p>Bolso de hombro elegante para mujer<\/p>\n","protected":false},"excerpt":{"rendered":"<h2><strong>Cartera Bolso Cruzado para Dama<\/strong><\/h2>\n<p>Caracteristicas<\/p>\n<ul>\n<li>Bolso de hombro elegante para mujer<\/li>\n<li>De alta calidad, vers\u00e1til, estilo cruzado y bolso de mano.<\/li>\n<li>Cierre con cremallera, Material Cuero PU, forro de poli\u00e9ster.<\/li>\n<li>ideal para viajes y regalos, disponible verde militar.<\/li>\n<\/ul>\n","protected":false},"featured_media":6932,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[313,332,314,331,276],"product_tag":[],"class_list":["post-6929","product","type-product","status-publish","has-post-thumbnail","product_cat-accesorios","product_cat-bolsos-cartera-cangureras-mochilas","product_cat-carteras-bolsos-y-mochilas","product_cat-explora-cientos-de-productos","product_cat-mujer","first","instock","virtual","purchasable","product-type-simple","add-to-wishlist-after_add_to_cart"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.ljsexpress.com\/es_pe\/wp-json\/wp\/v2\/product\/6929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ljsexpress.com\/es_pe\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ljsexpress.com\/es_pe\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ljsexpress.com\/es_pe\/wp-json\/wp\/v2\/comments?post=6929"}],"version-history":[{"count":3,"href":"https:\/\/www.ljsexpress.com\/es_pe\/wp-json\/wp\/v2\/product\/6929\/revisions"}],"predecessor-version":[{"id":6935,"href":"https:\/\/www.ljsexpress.com\/es_pe\/wp-json\/wp\/v2\/product\/6929\/revisions\/6935"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ljsexpress.com\/es_pe\/wp-json\/wp\/v2\/media\/6932"}],"wp:attachment":[{"href":"https:\/\/www.ljsexpress.com\/es_pe\/wp-json\/wp\/v2\/media?parent=6929"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.ljsexpress.com\/es_pe\/wp-json\/wp\/v2\/product_cat?post=6929"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.ljsexpress.com\/es_pe\/wp-json\/wp\/v2\/product_tag?post=6929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}